{"id":27155,"date":"2025-11-26T02:11:20","date_gmt":"2025-11-26T02:11:20","guid":{"rendered":"https:\/\/nacrystal.com\/?post_type=product&#038;p=27155"},"modified":"2026-06-16T19:53:43","modified_gmt":"2026-06-16T19:53:43","slug":"multifaceted-egg-shape-stone-rings","status":"publish","type":"product","link":"https:\/\/nacrystal.com\/ar\/product\/multifaceted-egg-shape-stone-rings\/","title":{"rendered":"\u062e\u0648\u0627\u062a\u0645 \u062d\u062c\u0631\u064a\u0629 \u0645\u062a\u0639\u062f\u062f\u0629 \u0627\u0644\u0623\u0648\u062c\u0647 \u0642\u0627\u0628\u0644\u0629 \u0644\u0644\u062a\u0639\u062f\u064a\u0644 \u0639\u0644\u0649 \u0634\u0643\u0644 \u0628\u064a\u0636\u0629 \u0628\u0627\u0644\u062c\u0645\u0644\u0629"},"content":{"rendered":"<div class=\"row\"  id=\"row-1174867910\">\n\n\t<div id=\"col-1115578718\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1277315117\" class=\"text\">\n\t\t\n<ul>\n<li><span style=\"font-size: 115%;\">\u0627\u0644\u0634\u0643\u0644: \u0634\u0643\u0644 \u0628\u064a\u0636\u0629<\/span><\/li>\n<li><span style=\"font-size: 115%;\">\u0627\u0644\u062d\u062c\u0645: \u0642\u0627\u0628\u0644 \u0644\u0644\u062a\u0639\u062f\u064a\u0644<\/span><\/li>\n<li><span style=\"font-size: 115%;\">\u0627\u0644\u062d\u062c\u0631: \u0627\u0644\u064a\u0634\u0628 \u0627\u0644\u0623\u062d\u0645\u0631\u060c \u0627\u0644\u062c\u0645\u0634\u062a\u060c \u0627\u0644\u0643\u0648\u0627\u0631\u062a\u0632 \u0627\u0644\u0648\u0631\u062f\u064a\u060c \u0627\u0644\u0644\u0627\u0632\u0648\u0631\u062f\u060c \u0627\u0644\u0639\u0642\u064a\u0642 \u0627\u0644\u0623\u0633\u0648\u062f\u060c \u0639\u064a\u0646 \u0627\u0644\u0646\u0645\u0631\u060c \u0627\u0644\u0623\u0641\u064a\u0646\u062a\u0648\u0631\u064a\u0646\u060c \u0627\u0644\u0644\u0627\u0628\u0631\u0627\u062f\u0648\u0631\u064a\u062a\u060c \u0627\u0644\u0631\u0645\u0644 \u0627\u0644\u0623\u0632\u0631\u0642<\/span><\/li>\n<li><span style=\"font-size: 115%;\">\u0627\u0644\u0637\u0644\u0627\u0621: \u0645\u0637\u0644\u064a \u0628\u0627\u0644\u0628\u0644\u0627\u062a\u064a\u0646<\/span><\/li>\n<li><span style=\"font-size: 115%;\">\u064a\u062c\u0645\u0639 \u0627\u0644\u062e\u0627\u062a\u0645 \u0627\u0644\u062d\u062c\u0631\u064a \u0639\u0644\u0649 \u0634\u0643\u0644 \u0628\u064a\u0636\u0629 \u0628\u064a\u0646 \u0627\u0644\u062d\u062c\u0631 \u0627\u0644\u0637\u0628\u064a\u0639\u064a \u0648\u0646\u0648\u0639 \u0627\u0644\u062e\u0627\u062a\u0645 \u0627\u0644\u0643\u0644\u0627\u0633\u064a\u0643\u064a\u060c \u0648\u0644\u0627 \u062a\u0642\u062a\u0635\u0631 \u0647\u0630\u0647 \u0627\u0644\u062e\u0648\u0627\u062a\u0645 \u0627\u0644\u0643\u0631\u064a\u0633\u062a\u0627\u0644\u064a\u0629 \u0627\u0644\u0646\u0633\u0627\u0626\u064a\u0629 \u0639\u0644\u0649 \u0625\u0638\u0647\u0627\u0631 \u0630\u0648\u0642\u0643 \u0641\u062d\u0633\u0628\u060c \u0628\u0644 \u062a\u062a\u0645\u062a\u0639 \u0623\u064a\u0636\u064b\u0627 \u0628\u062e\u0635\u0627\u0626\u0635 \u0639\u0644\u0627\u062c\u064a\u0629.<\/span><\/li>\n<\/ul>\n<div>\u00a0<\/div>\n\t\t\n<style>\n#text-1277315117 {\n  color: rgb(0,0,0);\n}\n#text-1277315117 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2014264260\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2031654581\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-10-800x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-10-800x800.jpg 800w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-10-400x400.jpg 400w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-10-280x280.jpg 280w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-10-768x768.jpg 768w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-10-12x12.jpg 12w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-10-100x100.jpg 100w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-10.jpg 920w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2031654581 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-734259126\">\n\n\t<div id=\"col-953148925\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1077194525\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-13-800x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-13-800x800.jpg 800w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-13-400x400.jpg 400w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-13-280x280.jpg 280w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-13-768x768.jpg 768w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-13-12x12.jpg 12w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-13-100x100.jpg 100w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-13.jpg 920w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1077194525 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1196466478\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1678281015\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-6-800x800.jpg\" class=\"attachment-large size-large\" alt=\"blue sand Adjustable Multifaceted Egg Shape Stone Rings Wholesale (6)\" srcset=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-6-800x800.jpg 800w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-6-400x400.jpg 400w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-6-280x280.jpg 280w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-6-768x768.jpg 768w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-6-12x12.jpg 12w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-6-100x100.jpg 100w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-6.jpg 920w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1678281015 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1863515220\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_326305660\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-8-800x800.jpg\" class=\"attachment-large size-large\" alt=\"Adjustable Multifaceted Egg Shape Stone Rings Wholesale--rose quartz\" srcset=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-8-800x800.jpg 800w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-8-400x400.jpg 400w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-8-280x280.jpg 280w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-8-768x768.jpg 768w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-8-12x12.jpg 12w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-8-100x100.jpg 100w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-8.jpg 920w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_326305660 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":27157,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[],"product_cat":[346,354],"product_tag":[],"class_list":["post-27155","product","type-product","status-publish","has-post-thumbnail","product_cat-crystal-rings","product_cat-rings","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"uagb_featured_image_src":{"full":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-1.jpg",920,920,false],"thumbnail":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-1-280x280.jpg",280,280,true],"medium":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-1-400x400.jpg",400,400,true],"medium_large":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-1-768x768.jpg",768,768,true],"large":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-1-800x800.jpg",800,800,true],"1536x1536":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-1.jpg",920,920,false],"2048x2048":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-1.jpg",920,920,false],"trp-custom-language-flag":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-1-12x12.jpg",12,12,true],"woocommerce_thumbnail":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-1.jpg",920,920,false],"woocommerce_single":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-1.jpg",920,920,false],"woocommerce_gallery_thumbnail":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/11\/Adjustable-Multifaceted-Egg-Shape-Stone-Rings-Wholesale-1-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"Kimm","author_link":"https:\/\/nacrystal.com\/ar\/author\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/nacrystal.com\/ar\/wp-json\/wp\/v2\/product\/27155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nacrystal.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nacrystal.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/nacrystal.com\/ar\/wp-json\/wp\/v2\/comments?post=27155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nacrystal.com\/ar\/wp-json\/wp\/v2\/media\/27157"}],"wp:attachment":[{"href":"https:\/\/nacrystal.com\/ar\/wp-json\/wp\/v2\/media?parent=27155"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nacrystal.com\/ar\/wp-json\/wp\/v2\/product_brand?post=27155"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nacrystal.com\/ar\/wp-json\/wp\/v2\/product_cat?post=27155"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nacrystal.com\/ar\/wp-json\/wp\/v2\/product_tag?post=27155"}],"curies":[{"name":"\u062f\u0628\u0644\u064a\u0648 \u0628\u064a","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}