{"id":29201,"date":"2026-03-23T10:01:58","date_gmt":"2026-03-23T10:01:58","guid":{"rendered":"https:\/\/nacrystal.com\/?post_type=product&#038;p=29201"},"modified":"2026-06-08T09:29:39","modified_gmt":"2026-06-08T09:29:39","slug":"dragon-head-crystal","status":"publish","type":"product","link":"https:\/\/nacrystal.com\/fi\/tuote\/dragon-head-crystal\/","title":{"rendered":"5 Types Carved Dragon Head Crystal"},"content":{"rendered":"<div class=\"row align-middle\"  id=\"row-237396623\">\n\n\t<div id=\"col-1472290938\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_68089009\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-3.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-3.jpg 800w, https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-3-400x400.jpg 400w, https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-3-280x280.jpg 280w, https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-3-768x768.jpg 768w, https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-3-12x12.jpg 12w, https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-3-100x100.jpg 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_68089009 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-637269639\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 105%; color: #000000;\">Material: Red obsidian\/ green aventurine\/ opal\/ Qinghai jade\/ yellow calcite<\/span><\/p>\n<p><span style=\"font-size: 105%; color: #000000;\">M\u00e4\u00e4r\u00e4: 1 kpl<\/span><\/p>\n<p><span style=\"font-size: 105%; color: #000000;\">The intricately carved dragon head crystal is versatile and can be used as a decorative item as well as for balancing energy.<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-91866106\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1902904223\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-4.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-4.jpg 800w, https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-4-400x400.jpg 400w, https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-4-280x280.jpg 280w, https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-4-768x768.jpg 768w, https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-4-12x12.jpg 12w, https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-4-100x100.jpg 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1902904223 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div>","protected":false},"excerpt":{"rendered":"<p><br data-mce-bogus=\"1\"><\/p>","protected":false},"featured_media":29204,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[],"product_cat":[393],"product_tag":[],"class_list":["post-29201","product","type-product","status-publish","has-post-thumbnail","product_cat-crystal-carvings","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"uagb_featured_image_src":{"full":["https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-2.jpg",800,800,false],"thumbnail":["https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-2-280x280.jpg",280,280,true],"medium":["https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-2-400x400.jpg",400,400,true],"medium_large":["https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-2-768x768.jpg",768,768,true],"large":["https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-2.jpg",800,800,false],"1536x1536":["https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-2.jpg",800,800,false],"2048x2048":["https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-2.jpg",800,800,false],"trp-custom-language-flag":["https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-2-12x12.jpg",12,12,true],"woocommerce_thumbnail":["https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-2.jpg",800,800,false],"woocommerce_single":["https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-2.jpg",800,800,false],"woocommerce_gallery_thumbnail":["https:\/\/nacrystal.com\/wp-content\/uploads\/2026\/03\/5-Types-Carved-Dragon-Head-Crystal-2-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"XMR","author_link":"https:\/\/nacrystal.com\/fi\/author\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/nacrystal.com\/fi\/wp-json\/wp\/v2\/product\/29201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nacrystal.com\/fi\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nacrystal.com\/fi\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/nacrystal.com\/fi\/wp-json\/wp\/v2\/comments?post=29201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nacrystal.com\/fi\/wp-json\/wp\/v2\/media\/29204"}],"wp:attachment":[{"href":"https:\/\/nacrystal.com\/fi\/wp-json\/wp\/v2\/media?parent=29201"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nacrystal.com\/fi\/wp-json\/wp\/v2\/product_brand?post=29201"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nacrystal.com\/fi\/wp-json\/wp\/v2\/product_cat?post=29201"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nacrystal.com\/fi\/wp-json\/wp\/v2\/product_tag?post=29201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}