{"id":25361,"date":"2025-09-25T08:58:32","date_gmt":"2025-09-25T08:58:32","guid":{"rendered":"https:\/\/nacrystal.com\/?post_type=product&#038;p=25361"},"modified":"2025-11-12T12:16:35","modified_gmt":"2025-11-12T12:16:35","slug":"horse-eye-blue-topaz-diamond-necklace","status":"publish","type":"product","link":"https:\/\/nacrystal.com\/ko\/product\/horse-eye-blue-topaz-diamond-necklace\/","title":{"rendered":"\ud638\uc2a4 \uc544\uc774 925 \uc2a4\ud138\ub9c1 \uc2e4\ubc84 \ube14\ub8e8 \ud1a0\ud30c\uc988 \ub2e4\uc774\uc544\ubaac\ub4dc \ubaa9\uac78\uc774"},"content":{"rendered":"<div class=\"row\"  id=\"row-206884428\">\n\n\t<div id=\"col-1536705540\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3306535427\" class=\"text\">\n\t\t\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\uc18c\uc7ac: S925 \uc2e4\ubc84 + \ube14\ub8e8 \ud1a0\ud30c\uc988<br \/>\uacf5\uc815: \ub450\uaebc\uc6b4 \uc804\uae30 \ub3c4\uae08<br \/>\ud39c\ub358\ud2b8 \ud06c\uae30: 9*15mm\/0.35*0.59\uc778\uce58<br \/>\ub2e4\uc774\uc544\ubaac\ub4dc \ud06c\uae30: 5*10mm\/0.2*39\uc778\uce58<br \/>\ud0c4\uc0dd\uc11d \ub2ec: 12\uc6d4<\/p>\n<p>\uc774 \ube14\ub8e8 \ud1a0\ud30c\uc988 \ub2e4\uc774\uc544\ubaac\ub4dc \ubaa9\uac78\uc774\ub294 925 \uc2a4\ud138\ub9c1 \uc2e4\ubc84\uc640 \ucc9c\uc5f0 \ud1a0\ud30c\uc988 \uc2a4\ud1a4\uc73c\ub85c \uc815\uad50\ud558\uac8c \uc81c\uc791\ub418\uc5c8\uc73c\uba70, \uc774\ub294 \ubbff\uc74c, \ud589\uc6b4, \uadf8\ub9ac\uace0 \uc21c\uc218\ud55c \uc0ac\ub791\uc744 \uc0c1\uc9d5\ud569\ub2c8\ub2e4.<\/p>\n<p>\uc774 \ube14\ub8e8 \ud1a0\ud30c\uc988 \ub2e4\uc774\uc544\ubaac\ub4dc \ubaa9\uac78\uc774\ub97c \uc0ac\ub791\ud558\ub294 \uc774\ub97c \uc704\ud55c \ubd80\uc801\uc73c\ub85c \uc0bc\uc544, \ud2b9\ubcc4\ud55c \uc120\ubb3c\ub85c \uadf8\ub140\/\ub2f9\uc2e0\uc758 \uc0dd\uc77c\uc744 \ucd95\ud558\ud558\uc138\uc694.<\/p>\n\t\t\n<style>\n#text-3306535427 {\n  color: rgb(0,0,0);\n}\n#text-3306535427 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1496345887\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1302895036\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-5.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-5.jpg 800w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-5-400x400.jpg 400w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-5-280x280.jpg 280w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-5-768x768.jpg 768w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-5-12x12.jpg 12w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-5-100x100.jpg 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1302895036 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1348522768\">\n\n\t<div id=\"col-1767789284\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_567064529\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-2.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-2.jpg 800w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-2-400x400.jpg 400w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-2-280x280.jpg 280w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-2-768x768.jpg 768w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-2-12x12.jpg 12w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-2-100x100.jpg 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_567064529 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1866327513\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1868184191\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-1.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-1.jpg 800w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-1-400x400.jpg 400w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-1-280x280.jpg 280w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-1-768x768.jpg 768w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-1-12x12.jpg 12w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1868184191 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1194293146\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_567079381\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-4.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-4.jpg 800w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-4-400x400.jpg 400w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-4-280x280.jpg 280w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-4-768x768.jpg 768w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-4-12x12.jpg 12w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-4-100x100.jpg 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_567079381 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":25366,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[],"product_cat":[1170],"product_tag":[],"class_list":["post-25361","product","type-product","status-publish","has-post-thumbnail","product_cat-blue-topaz-birthstone","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"uagb_featured_image_src":{"full":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-3.jpg",800,800,false],"thumbnail":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-3-280x280.jpg",280,280,true],"medium":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-3-400x400.jpg",400,400,true],"medium_large":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-3-768x768.jpg",768,768,true],"large":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-3.jpg",800,800,false],"1536x1536":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-3.jpg",800,800,false],"2048x2048":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-3.jpg",800,800,false],"trp-custom-language-flag":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-3-12x12.jpg",12,12,true],"woocommerce_thumbnail":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-3.jpg",800,800,false],"woocommerce_single":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-3.jpg",800,800,false],"woocommerce_gallery_thumbnail":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Horse-Eye-925-Sterling-Silver-Blue-Topaz-Diamond-Necklace\u200b-3-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"Kimm","author_link":"https:\/\/nacrystal.com\/ko\/author\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/nacrystal.com\/ko\/wp-json\/wp\/v2\/product\/25361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nacrystal.com\/ko\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nacrystal.com\/ko\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/nacrystal.com\/ko\/wp-json\/wp\/v2\/comments?post=25361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nacrystal.com\/ko\/wp-json\/wp\/v2\/media\/25366"}],"wp:attachment":[{"href":"https:\/\/nacrystal.com\/ko\/wp-json\/wp\/v2\/media?parent=25361"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nacrystal.com\/ko\/wp-json\/wp\/v2\/product_brand?post=25361"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nacrystal.com\/ko\/wp-json\/wp\/v2\/product_cat?post=25361"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nacrystal.com\/ko\/wp-json\/wp\/v2\/product_tag?post=25361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}