{"id":25195,"date":"2025-09-24T07:53:02","date_gmt":"2025-09-24T07:53:02","guid":{"rendered":"https:\/\/nacrystal.com\/?post_type=product&#038;p=25195"},"modified":"2026-05-23T05:15:24","modified_gmt":"2026-05-23T05:15:24","slug":"round-blue-topaz-loose-stone","status":"publish","type":"product","link":"https:\/\/nacrystal.com\/sv\/produkt\/round-blue-topaz-loose-stone\/","title":{"rendered":"\u00c4kta rundslipad bl\u00e5 topas, l\u00f6s sten"},"content":{"rendered":"<div class=\"row align-middle\"  id=\"row-1261833290\">\n\n\t<div id=\"col-1772178757\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1939161248\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1-800x800.jpg\" class=\"attachment-large size-large\" alt=\"Genuine Round Cut Blue Topaz Loose Stone\" srcset=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1-800x800.jpg 800w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1-400x400.jpg 400w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1-280x280.jpg 280w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1-768x768.jpg 768w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1-12x12.jpg 12w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1-1024x1024.jpg 1024w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1-100x100.jpg 100w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1.jpg 1280w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1939161248 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-252799491\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 105%; color: #000000;\"><strong>Specifikation<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"font-size: 105%; color: #000000;\">F\u00f6delsestenm\u00e5nad: december<\/span><\/li>\n<li><span style=\"font-size: 105%; color: #000000;\">Material: Topas<\/span><\/li>\n<li><span style=\"font-size: 105%; color: #000000;\">Typ: Naturlig<\/span><\/li>\n<li><span style=\"font-size: 105%; color: #000000;\">F\u00e4rg: Bl\u00e5<\/span><\/li>\n<li><span style=\"font-size: 105%; color: #000000;\">Antal: 1 st<\/span><\/li>\n<li><span style=\"font-size: 105%; color: #000000;\">Storlek: 3\u20138 mm\/0,12\u20130,315 tum<\/span><\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2077463854\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_540379638\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-5.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-5.jpg 800w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-5-400x400.jpg 400w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-5-280x280.jpg 280w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-5-768x768.jpg 768w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-5-12x12.jpg 12w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-5-100x100.jpg 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_540379638 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<p><span style=\"font-size: 105%; color: #000000;\">Rundheten \u00e4r en klassisk slipningsform, som ocks\u00e5 g\u00f6r att energin i bl\u00e5 topas kan f\u00f6rdelas j\u00e4mnt i alla riktningar. Rundslipad bl\u00e5 topas i l\u00f6s sten \u00e4r mycket l\u00e4mplig f\u00f6r DIY-ringar, \u00f6rh\u00e4ngen och andra smycken.<\/span><\/p>\n<p><span style=\"font-size: 105%; color: #000000;\">Bl\u00e5 topas kan hj\u00e4lpa till att \u00f6ka uppm\u00e4rksamheten, f\u00f6rb\u00e4ttra insikten och sk\u00e4rpan i t\u00e4nkandet.<\/span><\/p>\n<p><span style=\"font-size: 105%; color: #000000;\">Bl\u00e5 topas \u00e4r december m\u00e5nads f\u00f6delsesten. Ge den i present till n\u00e5gon som fyller \u00e5r i december f\u00f6r att symbolisera lycka och ett l\u00e5ngt liv.<\/span><\/p>\n<div class=\"row\"  id=\"row-144644911\">\n\n\t<div id=\"col-1014868202\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_571859185\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-4.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-4.jpg 800w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-4-400x400.jpg 400w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-4-280x280.jpg 280w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-4-768x768.jpg 768w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-4-12x12.jpg 12w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-4-100x100.jpg 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_571859185 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-918042560\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_486989487\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-2.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-2.jpg 800w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-2-400x400.jpg 400w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-2-280x280.jpg 280w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-2-768x768.jpg 768w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-2-12x12.jpg 12w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-2-100x100.jpg 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_486989487 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-226272747\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1640893524\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-3.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-3.jpg 800w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-3-400x400.jpg 400w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-3-280x280.jpg 280w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-3-768x768.jpg 768w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-3-12x12.jpg 12w, https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-3-100x100.jpg 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1640893524 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div>","protected":false},"excerpt":{"rendered":"<p>The roundness is a classic cutting shape, which also enables the energy of blue topaz to be evenly distributed in all directions. Round cut blue topaz loose stone is very suitable for diy rings, stud earrings and other jewelry. Blue topaz can help enhance attention, improve insight and the acuity of thinking. Blue topaz is<\/p>","protected":false},"featured_media":25197,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[],"product_cat":[1170],"product_tag":[],"class_list":["post-25195","product","type-product","status-publish","has-post-thumbnail","product_cat-blue-topaz-birthstone","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"uagb_featured_image_src":{"full":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1.jpg",1280,1280,false],"thumbnail":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1-280x280.jpg",280,280,true],"medium":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1-400x400.jpg",400,400,true],"medium_large":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1-768x768.jpg",768,768,true],"large":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1-800x800.jpg",800,800,true],"1536x1536":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1.jpg",1280,1280,false],"2048x2048":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1.jpg",1280,1280,false],"trp-custom-language-flag":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1-12x12.jpg",12,12,true],"woocommerce_thumbnail":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1-1024x1024.jpg",1024,1024,true],"woocommerce_single":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1-1024x1024.jpg",1024,1024,true],"woocommerce_gallery_thumbnail":["https:\/\/nacrystal.com\/wp-content\/uploads\/2025\/09\/Genuine-Round-Cut-Blue-Topaz-Loose-Stone-1-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"XMR","author_link":"https:\/\/nacrystal.com\/sv\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"The roundness is a classic cutting shape, which also enables the energy of blue topaz to be evenly distributed in all directions. Round cut blue topaz loose stone is very suitable for diy rings, stud earrings and other jewelry. Blue topaz can help enhance attention, improve insight and the acuity of thinking. Blue topaz is","_links":{"self":[{"href":"https:\/\/nacrystal.com\/sv\/wp-json\/wp\/v2\/product\/25195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nacrystal.com\/sv\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nacrystal.com\/sv\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/nacrystal.com\/sv\/wp-json\/wp\/v2\/comments?post=25195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nacrystal.com\/sv\/wp-json\/wp\/v2\/media\/25197"}],"wp:attachment":[{"href":"https:\/\/nacrystal.com\/sv\/wp-json\/wp\/v2\/media?parent=25195"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nacrystal.com\/sv\/wp-json\/wp\/v2\/product_brand?post=25195"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nacrystal.com\/sv\/wp-json\/wp\/v2\/product_cat?post=25195"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nacrystal.com\/sv\/wp-json\/wp\/v2\/product_tag?post=25195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}